{"id":2641,"date":"2024-06-24T15:24:45","date_gmt":"2024-06-24T15:24:45","guid":{"rendered":"https:\/\/eco-bois-alsace.fr\/warum-eiche-als-brennholz\/"},"modified":"2024-07-05T10:24:25","modified_gmt":"2024-07-05T10:24:25","slug":"warum-eiche-als-brennholz","status":"publish","type":"post","link":"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/","title":{"rendered":"Warum Eiche als Brennholz?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2641\" class=\"elementor elementor-2641\" data-elementor-post-type=\"post\">\n\t\t\t\t<section class=\"elementor-element elementor-element-87176da bg-light-color e-flex e-con-boxed e-con e-parent\" data-id=\"87176da\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a46553 elementor-widget elementor-widget-text-editor\" data-id=\"7a46553\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><\/p>\n<p>Sie m\u00f6chten <a href=\"https:\/\/www.eco-bois-alsace.fr\/nos-prestations\/livraison-de-bois-de-chauffage-dans-le-haut-rhin-68\/\">\n  <strong>Ihre Eichenst\u00e4mme bestellen<\/strong>\n<\/a> f\u00fcr die Beheizung Ihrer Wohnung? Ein Haus mit einem Kamin oder Holzofen zu beheizen ist angenehm und gem\u00fctlich.<\/p>\n<p>Unser Unternehmen<strong> Eco Bois Alsace<\/strong> liefert Brennholz verschiedener Holzarten und Qualit\u00e4ten aus der Trocknung in die Gegend von <strong>Mulhouse<\/strong> im Departement <strong>Haut-Rhin<\/strong>. Wir geben Ihnen alle <strong>Gr\u00fcnde, sich f\u00fcr Eiche als Brennholz zu entscheiden<\/strong>.<\/p>\n<p><\/p>\n<p><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<section class=\"elementor-element elementor-element-377b50b bg-light-color e-flex e-con-boxed e-con e-parent\" data-id=\"377b50b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d6a3fd elementor-widget elementor-widget-text-editor\" data-id=\"0d6a3fd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><\/p>\n<h2>Eiche, eines der besten Brennh\u00f6lzer<\/h2>\n<p><\/p>\n<p><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<section class=\"elementor-element elementor-element-d6155ff bg-light-color e-grid e-con-boxed e-con e-parent\" data-id=\"d6155ff\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3930934 elementor-widget elementor-widget-text-editor\" data-id=\"3930934\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><\/p>\n<p><\/p>\n<h3>Die Eigenschaften der Eiche<\/h3>\n<p>Die <strong>Eiche<\/strong> geh\u00f6rt zu mehreren Arten wie :<\/p>\n<ul>\n<li>Roteiche ;<\/li>\n<li>die Haarige Eiche ;<\/li>\n<li>Flaumeiche.<\/li>\n<\/ul>\n<p>Mit seiner hohen Dichte und Festigkeit ist Eiche ein ideales Holz f\u00fcr den Bau von Dachst\u00fchlen und anderen starken Strukturen.<\/p>\n<p>Diese Eigenschaften machen es zu einem Holz, das sich hervorragend f\u00fcr eine Verwendung wie die Verbrennung zum Heizen von Wohnr\u00e4umen eignet, da es eine gro\u00dfe W\u00e4rme abgibt und lange brennt.<\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6830b8 elementor-widget elementor-widget-text-editor\" data-id=\"b6830b8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><\/p>\n<p><\/p>\n<h3>Der Ertrag von Eiche<\/h3>\n<p>Alle <strong>Brennh\u00f6lzer<\/strong> werden nach ihrer Leistung klassifiziert:<\/p>\n<ul>\n<li>G1: Hartholz ;<\/li>\n<li>G2: mittelhartes und weiches Laubholz ;<\/li>\n<li>G3: Nadelholz.<\/li>\n<\/ul>\n<p>Hartes Laubholz ist am besten als <strong>Brennholz<\/strong> geeignet, da es eine lange Brenndauer hat und intensiv brennt.<\/p>\n<p>Alle <strong>Eichenarten<\/strong> werden als harte Laubb\u00e4ume klassifiziert und sind daher ideal zum Heizen geeignet.<\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<section class=\"elementor-element elementor-element-d962b7d bg-light-color e-grid e-con-boxed e-con e-parent\" data-id=\"d962b7d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69ecef7 elementor-widget elementor-widget-text-editor\" data-id=\"69ecef7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><\/p>\n<p><\/p>\n<h3>Trockenes Holz f\u00fcr die Heizung<\/h3>\n<p>Um Ihre Wohnung effizient zu heizen, muss das gew\u00e4hlte <strong>Brennholz<\/strong> so trocken wie m\u00f6glich sein.<\/p>\n<p>Holz, das mit Feuchtigkeit gef\u00fcllt ist, brennt nicht so leicht und brennt nicht so lange. Es gibt nicht die gleiche W\u00e4rme ab wie trockenes Holz.<\/p>\n<p>Bevorzugen Sie daher eine trockene <strong>Eiche<\/strong> oder lassen Sie sie trocknen, wenn sie nicht trocken genug ist.<\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<section class=\"elementor-element elementor-element-c6ece79 bg-light-color e-flex e-con-boxed e-con e-parent\" data-id=\"c6ece79\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-af0e2a8 elementor-widget elementor-widget-text-editor\" data-id=\"af0e2a8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><\/p>\n<h2>Eco Bois Alsace: Ihr Holzh\u00e4ndler rund um Mulhouse im Haut-Rhin<\/h2>\n<p>M\u00f6chten Sie <strong>Eichenholz<\/strong> kaufen, um Ihre Wohnung zu heizen? Unser Unternehmen <strong>Eco Bois Alsace<\/strong> bietet Brennholz aller Holzarten und verschiedener Trocknungsqualit\u00e4ten in der Gegend von <strong>Mulhouse<\/strong> im Departement <strong>Haut-Rhin<\/strong> zum Verkauf an.<\/p>\n<p><a href=\"https:\/\/www.eco-bois-alsace.fr\/contactez-nous\/\">KONTAKTIEREN SIE UNS<\/a><\/p>\n<p><\/p>\n<p><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<section class=\"elementor-element elementor-element-425668f bg-light-color e-flex e-con-boxed e-con e-parent\" data-id=\"425668f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sie m\u00f6chten Ihre Eichenst\u00e4mme bestellen f\u00fcr die Beheizung Ihrer Wohnung? Ein Haus mit einem Kamin oder Holzofen zu beheizen ist angenehm und gem\u00fctlich. Unser Unternehmen Eco Bois Alsace liefert Brennholz verschiedener Holzarten und Qualit\u00e4ten aus der Trocknung in die Gegend von Mulhouse im Departement Haut-Rhin. Wir geben Ihnen alle Gr\u00fcnde, sich f\u00fcr Eiche als Brennholz [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2317,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Warum Eiche als Brennholz? - Eco Bois Alsace<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Warum Eiche als Brennholz? - Eco Bois Alsace\" \/>\n<meta property=\"og:description\" content=\"Sie m\u00f6chten Ihre Eichenst\u00e4mme bestellen f\u00fcr die Beheizung Ihrer Wohnung? Ein Haus mit einem Kamin oder Holzofen zu beheizen ist angenehm und gem\u00fctlich. Unser Unternehmen Eco Bois Alsace liefert Brennholz verschiedener Holzarten und Qualit\u00e4ten aus der Trocknung in die Gegend von Mulhouse im Departement Haut-Rhin. Wir geben Ihnen alle Gr\u00fcnde, sich f\u00fcr Eiche als Brennholz [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/\" \/>\n<meta property=\"og:site_name\" content=\"Eco Bois Alsace\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-24T15:24:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-05T10:24:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Pourquoi-opter-pour-le-chene-comme-bois-de-chauffage.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1078\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Fiona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fiona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/\"},\"author\":{\"name\":\"Fiona\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#\/schema\/person\/aea1369e07e4db485e2191cc39356ff0\"},\"headline\":\"Warum Eiche als Brennholz?\",\"datePublished\":\"2024-06-24T15:24:45+00:00\",\"dateModified\":\"2024-07-05T10:24:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/\"},\"wordCount\":315,\"publisher\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Pourquoi-opter-pour-le-chene-comme-bois-de-chauffage.webp\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/\",\"url\":\"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/\",\"name\":\"Warum Eiche als Brennholz? - Eco Bois Alsace\",\"isPartOf\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Pourquoi-opter-pour-le-chene-comme-bois-de-chauffage.webp\",\"datePublished\":\"2024-06-24T15:24:45+00:00\",\"dateModified\":\"2024-07-05T10:24:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/#primaryimage\",\"url\":\"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Pourquoi-opter-pour-le-chene-comme-bois-de-chauffage.webp\",\"contentUrl\":\"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Pourquoi-opter-pour-le-chene-comme-bois-de-chauffage.webp\",\"width\":1920,\"height\":1078},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/eco-bois-alsace.fr\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Warum Eiche als Brennholz?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#website\",\"url\":\"https:\/\/eco-bois-alsace.fr\/de\/\",\"name\":\"Eco Bois Alsace\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eco-bois-alsace.fr\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#organization\",\"name\":\"Eco Bois Alsace\",\"url\":\"https:\/\/eco-bois-alsace.fr\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Logo-blanc_ecoboisalsace.png\",\"contentUrl\":\"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Logo-blanc_ecoboisalsace.png\",\"width\":552,\"height\":152,\"caption\":\"Eco Bois Alsace\"},\"image\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#\/schema\/person\/aea1369e07e4db485e2191cc39356ff0\",\"name\":\"Fiona\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Warum Eiche als Brennholz? - Eco Bois Alsace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/","og_locale":"de_DE","og_type":"article","og_title":"Warum Eiche als Brennholz? - Eco Bois Alsace","og_description":"Sie m\u00f6chten Ihre Eichenst\u00e4mme bestellen f\u00fcr die Beheizung Ihrer Wohnung? Ein Haus mit einem Kamin oder Holzofen zu beheizen ist angenehm und gem\u00fctlich. Unser Unternehmen Eco Bois Alsace liefert Brennholz verschiedener Holzarten und Qualit\u00e4ten aus der Trocknung in die Gegend von Mulhouse im Departement Haut-Rhin. Wir geben Ihnen alle Gr\u00fcnde, sich f\u00fcr Eiche als Brennholz [&hellip;]","og_url":"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/","og_site_name":"Eco Bois Alsace","article_published_time":"2024-06-24T15:24:45+00:00","article_modified_time":"2024-07-05T10:24:25+00:00","og_image":[{"width":1920,"height":1078,"url":"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Pourquoi-opter-pour-le-chene-comme-bois-de-chauffage.webp","type":"image\/webp"}],"author":"Fiona","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Fiona","Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/#article","isPartOf":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/"},"author":{"name":"Fiona","@id":"https:\/\/eco-bois-alsace.fr\/de\/#\/schema\/person\/aea1369e07e4db485e2191cc39356ff0"},"headline":"Warum Eiche als Brennholz?","datePublished":"2024-06-24T15:24:45+00:00","dateModified":"2024-07-05T10:24:25+00:00","mainEntityOfPage":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/"},"wordCount":315,"publisher":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/#organization"},"image":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/#primaryimage"},"thumbnailUrl":"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Pourquoi-opter-pour-le-chene-comme-bois-de-chauffage.webp","articleSection":["Unkategorisiert"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/","url":"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/","name":"Warum Eiche als Brennholz? - Eco Bois Alsace","isPartOf":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/#primaryimage"},"image":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/#primaryimage"},"thumbnailUrl":"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Pourquoi-opter-pour-le-chene-comme-bois-de-chauffage.webp","datePublished":"2024-06-24T15:24:45+00:00","dateModified":"2024-07-05T10:24:25+00:00","breadcrumb":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/#primaryimage","url":"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Pourquoi-opter-pour-le-chene-comme-bois-de-chauffage.webp","contentUrl":"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Pourquoi-opter-pour-le-chene-comme-bois-de-chauffage.webp","width":1920,"height":1078},{"@type":"BreadcrumbList","@id":"https:\/\/eco-bois-alsace.fr\/de\/warum-eiche-als-brennholz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/eco-bois-alsace.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Warum Eiche als Brennholz?"}]},{"@type":"WebSite","@id":"https:\/\/eco-bois-alsace.fr\/de\/#website","url":"https:\/\/eco-bois-alsace.fr\/de\/","name":"Eco Bois Alsace","description":"","publisher":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eco-bois-alsace.fr\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/eco-bois-alsace.fr\/de\/#organization","name":"Eco Bois Alsace","url":"https:\/\/eco-bois-alsace.fr\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/eco-bois-alsace.fr\/de\/#\/schema\/logo\/image\/","url":"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Logo-blanc_ecoboisalsace.png","contentUrl":"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Logo-blanc_ecoboisalsace.png","width":552,"height":152,"caption":"Eco Bois Alsace"},"image":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eco-bois-alsace.fr\/de\/#\/schema\/person\/aea1369e07e4db485e2191cc39356ff0","name":"Fiona"}]}},"_links":{"self":[{"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/posts\/2641"}],"collection":[{"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/comments?post=2641"}],"version-history":[{"count":9,"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/posts\/2641\/revisions"}],"predecessor-version":[{"id":2662,"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/posts\/2641\/revisions\/2662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/media\/2317"}],"wp:attachment":[{"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/media?parent=2641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/categories?post=2641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/tags?post=2641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}