{"id":2354,"date":"2024-06-25T08:51:12","date_gmt":"2024-06-25T08:51:12","guid":{"rendered":"https:\/\/eco-bois-alsace.fr\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/"},"modified":"2024-07-05T09:55:18","modified_gmt":"2024-07-05T09:55:18","slug":"welches-holz-sollte-in-einem-kamin-verwendet-werden","status":"publish","type":"post","link":"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/","title":{"rendered":"Welches Holz sollte in einem Kamin verwendet werden?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2354\" class=\"elementor elementor-2354\" data-elementor-post-type=\"post\">\n\t\t\t\t<section class=\"elementor-element elementor-element-87176da bg-light-color e-flex e-con-boxed e-con e-parent\" data-id=\"87176da\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a46553 elementor-widget elementor-widget-text-editor\" data-id=\"7a46553\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><\/p>\n<p>Sie m\u00f6chten ein sch\u00f6nes Feuer entfachen, aber die Wahl des <strong>Holzes f\u00fcr Ihren Kamin<\/strong> ist schwierig? Entdecken Sie die besten H\u00f6lzer f\u00fcr ein sch\u00f6nes Flambieren! Brauchen Sie Holzscheite? Unser Unternehmen <strong>Eco Bois Alsace<\/strong> verkauft und liefert Brennholz. <a href=\"https:\/\/www.eco-bois-alsace.fr\/actualites\/quel-bois-de-chauffage-choisir\/\">\n  <strong>Brennholz<\/strong>\n<\/a> in der Gegend von <strong>Mulhouse<\/strong> im Departement <strong>Haut-Rhin<\/strong>. Z\u00f6gern Sie nicht, Ihre Holzscheite zu bestellen!<\/p>\n<p><\/p>\n<p><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<section class=\"elementor-element elementor-element-377b50b bg-light-color e-flex e-con-boxed e-con e-parent\" data-id=\"377b50b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d6a3fd elementor-widget elementor-widget-text-editor\" data-id=\"0d6a3fd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><\/p>\n<h2>Brennholz: die zu verwendenden Holzarten<\/h2>\n<p>M\u00f6chten Sie Ihr<strong>Kaminholz<\/strong> richtig ausw\u00e4hlen? Zun\u00e4chst sollten Sie wissen, dass <strong>Brennholz <\/strong>nicht gleich <strong>Brennholz <\/strong>ist. Je dichter das Holz, desto w\u00e4rmer und langlebiger das Feuer. Hier ist eine Klassifizierung der zu bevorzugenden Baumarten nach ihrer Dichte:<\/p>\n<ul>\n<li><strong>Hartholz <\/strong>: Es brennt langsam und erzeugt mehr W\u00e4rme. Es handelt sich um Buche, Ulme, Eiche, Hainbuche und Esche.<\/li>\n<li><strong>Mittelhartes Holz <\/strong>: Weniger w\u00e4rmend, wird wenig verwendet. Sie umfassen Obstb\u00e4ume, Kastanien und Robinien.<\/li>\n<li><strong>Weiches Holz <\/strong>: Es brennt leicht an und ist daher ideal zum Anz\u00fcnden. Es handelt sich um Birke, Ahorn, Erle, Linde, Pappel und Weide.<\/li>\n<\/ul>\n<p><\/p>\n<p><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<section class=\"elementor-element elementor-element-9790ba7 bg-light-color e-flex e-con-boxed e-con e-parent\" data-id=\"9790ba7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c39b2fa elementor-widget elementor-widget-text-editor\" data-id=\"c39b2fa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><\/p>\n<h2>Brennholz: Wie viel Feuchtigkeit?<\/h2>\n<p>Um optimal zu heizen, d.h. zu heizen und zu halten, aber auch um Ihre Anlage sauber zu halten, sollten Sie trockenes oder sogar sehr trockenes Holz bevorzugen. <strong>Feuchtes Holz <\/strong>heizt nur halb so viel wie <strong>trockenes Holz <\/strong>und verstopft den Schornstein schneller.<\/p>\n<p><\/p>\n<p><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<section class=\"elementor-element elementor-element-20b1e36 bg-light-color e-flex e-con-boxed e-con e-parent\" data-id=\"20b1e36\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-410d328 elementor-widget elementor-widget-text-editor\" data-id=\"410d328\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><\/p>\n<h2>Eco Bois Alsace, Ihr Lieferant von Brennholz in der N\u00e4he von Mulhouse im Departement Haut-Rhin.<\/h2>\n<p>Um die Qualit\u00e4t der Heizung, aber auch die Haltbarkeit Ihres Ger\u00e4tes zu gew\u00e4hrleisten, w\u00e4hlen Sie ein hochwertiges <strong>Kaminholz <\/strong>! <strong>Eco Bois Alsace<\/strong> ist auf die Verarbeitung und den Verkauf von <strong>Brennholz<\/strong> spezialisiert und liefert Ihnen das Holz, das Sie in der Umgebung von <strong>Mulhouse <\/strong>im Departement <strong>Haut-Rhin<\/strong> ben\u00f6tigen.<\/p>\n<p>Wir verpflichten uns, alle Ihre Erwartungen in Bezug auf Holzarten, Gr\u00f6\u00dfen und Feuchtigkeitsgehalt des Holzes zu erf\u00fcllen. Um Ihre Holzscheite zu erhalten, kommen Sie bitte in unser B\u00fcro oder lassen Sie sie sich liefern!<\/p>\n<p><\/p>\n<p><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-0146523 e-flex e-con-boxed e-con e-parent\" data-id=\"0146523\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sie m\u00f6chten ein sch\u00f6nes Feuer entfachen, aber die Wahl des Holzes f\u00fcr Ihren Kamin ist schwierig? Entdecken Sie die besten H\u00f6lzer f\u00fcr ein sch\u00f6nes Flambieren! Brauchen Sie Holzscheite? Unser Unternehmen Eco Bois Alsace verkauft und liefert Brennholz. Brennholz in der Gegend von Mulhouse im Departement Haut-Rhin. Z\u00f6gern Sie nicht, Ihre Holzscheite zu bestellen! Brennholz: die [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Welches Holz sollte in einem Kamin verwendet werden? - Eco Bois Alsace<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Welches Holz sollte in einem Kamin verwendet werden? - Eco Bois Alsace\" \/>\n<meta property=\"og:description\" content=\"Sie m\u00f6chten ein sch\u00f6nes Feuer entfachen, aber die Wahl des Holzes f\u00fcr Ihren Kamin ist schwierig? Entdecken Sie die besten H\u00f6lzer f\u00fcr ein sch\u00f6nes Flambieren! Brauchen Sie Holzscheite? Unser Unternehmen Eco Bois Alsace verkauft und liefert Brennholz. Brennholz in der Gegend von Mulhouse im Departement Haut-Rhin. Z\u00f6gern Sie nicht, Ihre Holzscheite zu bestellen! Brennholz: die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/\" \/>\n<meta property=\"og:site_name\" content=\"Eco Bois Alsace\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-25T08:51:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-05T09:55:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Quel-bois-utiliser-dans-une-cheminee.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1078\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Fiona\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fiona\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/\"},\"author\":{\"name\":\"Fiona\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#\/schema\/person\/aea1369e07e4db485e2191cc39356ff0\"},\"headline\":\"Welches Holz sollte in einem Kamin verwendet werden?\",\"datePublished\":\"2024-06-25T08:51:12+00:00\",\"dateModified\":\"2024-07-05T09:55:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/\"},\"wordCount\":323,\"publisher\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Quel-bois-utiliser-dans-une-cheminee.webp\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/\",\"url\":\"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/\",\"name\":\"Welches Holz sollte in einem Kamin verwendet werden? - Eco Bois Alsace\",\"isPartOf\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Quel-bois-utiliser-dans-une-cheminee.webp\",\"datePublished\":\"2024-06-25T08:51:12+00:00\",\"dateModified\":\"2024-07-05T09:55:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/#primaryimage\",\"url\":\"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Quel-bois-utiliser-dans-une-cheminee.webp\",\"contentUrl\":\"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Quel-bois-utiliser-dans-une-cheminee.webp\",\"width\":1920,\"height\":1078},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/eco-bois-alsace.fr\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Welches Holz sollte in einem Kamin verwendet werden?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#website\",\"url\":\"https:\/\/eco-bois-alsace.fr\/de\/\",\"name\":\"Eco Bois Alsace\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eco-bois-alsace.fr\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#organization\",\"name\":\"Eco Bois Alsace\",\"url\":\"https:\/\/eco-bois-alsace.fr\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Logo-blanc_ecoboisalsace.png\",\"contentUrl\":\"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Logo-blanc_ecoboisalsace.png\",\"width\":552,\"height\":152,\"caption\":\"Eco Bois Alsace\"},\"image\":{\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/eco-bois-alsace.fr\/de\/#\/schema\/person\/aea1369e07e4db485e2191cc39356ff0\",\"name\":\"Fiona\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Welches Holz sollte in einem Kamin verwendet werden? - Eco Bois Alsace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/","og_locale":"de_DE","og_type":"article","og_title":"Welches Holz sollte in einem Kamin verwendet werden? - Eco Bois Alsace","og_description":"Sie m\u00f6chten ein sch\u00f6nes Feuer entfachen, aber die Wahl des Holzes f\u00fcr Ihren Kamin ist schwierig? Entdecken Sie die besten H\u00f6lzer f\u00fcr ein sch\u00f6nes Flambieren! Brauchen Sie Holzscheite? Unser Unternehmen Eco Bois Alsace verkauft und liefert Brennholz. Brennholz in der Gegend von Mulhouse im Departement Haut-Rhin. Z\u00f6gern Sie nicht, Ihre Holzscheite zu bestellen! Brennholz: die [&hellip;]","og_url":"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/","og_site_name":"Eco Bois Alsace","article_published_time":"2024-06-25T08:51:12+00:00","article_modified_time":"2024-07-05T09:55:18+00:00","og_image":[{"width":1920,"height":1078,"url":"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Quel-bois-utiliser-dans-une-cheminee.webp","type":"image\/webp"}],"author":"Fiona","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Fiona","Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/#article","isPartOf":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/"},"author":{"name":"Fiona","@id":"https:\/\/eco-bois-alsace.fr\/de\/#\/schema\/person\/aea1369e07e4db485e2191cc39356ff0"},"headline":"Welches Holz sollte in einem Kamin verwendet werden?","datePublished":"2024-06-25T08:51:12+00:00","dateModified":"2024-07-05T09:55:18+00:00","mainEntityOfPage":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/"},"wordCount":323,"publisher":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/#organization"},"image":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/#primaryimage"},"thumbnailUrl":"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Quel-bois-utiliser-dans-une-cheminee.webp","articleSection":["Unkategorisiert"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/","url":"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/","name":"Welches Holz sollte in einem Kamin verwendet werden? - Eco Bois Alsace","isPartOf":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/#primaryimage"},"image":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/#primaryimage"},"thumbnailUrl":"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Quel-bois-utiliser-dans-une-cheminee.webp","datePublished":"2024-06-25T08:51:12+00:00","dateModified":"2024-07-05T09:55:18+00:00","breadcrumb":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/#primaryimage","url":"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Quel-bois-utiliser-dans-une-cheminee.webp","contentUrl":"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Quel-bois-utiliser-dans-une-cheminee.webp","width":1920,"height":1078},{"@type":"BreadcrumbList","@id":"https:\/\/eco-bois-alsace.fr\/de\/welches-holz-sollte-in-einem-kamin-verwendet-werden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/eco-bois-alsace.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Welches Holz sollte in einem Kamin verwendet werden?"}]},{"@type":"WebSite","@id":"https:\/\/eco-bois-alsace.fr\/de\/#website","url":"https:\/\/eco-bois-alsace.fr\/de\/","name":"Eco Bois Alsace","description":"","publisher":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eco-bois-alsace.fr\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/eco-bois-alsace.fr\/de\/#organization","name":"Eco Bois Alsace","url":"https:\/\/eco-bois-alsace.fr\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/eco-bois-alsace.fr\/de\/#\/schema\/logo\/image\/","url":"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Logo-blanc_ecoboisalsace.png","contentUrl":"https:\/\/eco-bois-alsace.fr\/wp-content\/uploads\/2024\/06\/Logo-blanc_ecoboisalsace.png","width":552,"height":152,"caption":"Eco Bois Alsace"},"image":{"@id":"https:\/\/eco-bois-alsace.fr\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eco-bois-alsace.fr\/de\/#\/schema\/person\/aea1369e07e4db485e2191cc39356ff0","name":"Fiona"}]}},"_links":{"self":[{"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/posts\/2354"}],"collection":[{"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/comments?post=2354"}],"version-history":[{"count":7,"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/posts\/2354\/revisions"}],"predecessor-version":[{"id":2379,"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/posts\/2354\/revisions\/2379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/media\/2324"}],"wp:attachment":[{"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/media?parent=2354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/categories?post=2354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eco-bois-alsace.fr\/de\/wp-json\/wp\/v2\/tags?post=2354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}